{"id":53059,"date":"2025-05-26T13:33:52","date_gmt":"2025-05-26T11:33:52","guid":{"rendered":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/"},"modified":"2025-05-26T13:33:52","modified_gmt":"2025-05-26T11:33:52","slug":"impetigo","status":"publish","type":"complaint","link":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/","title":{"rendered":"Impetigo"},"featured_media":0,"menu_order":9999,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[]},"complaint_tag":[421,922,923,548,408,924,925,416,926],"complaint_body_part":[96,554,283,558,97,284,560,561,562,564,494,565,567,568,570,454,496],"complaint_age_group":[98,99,100,101,102,103,104,105],"complaint_category":[4240,4252],"class_list":["post-53059","complaint","type-complaint","status-publish","hentry","complaint_category-infections-and-inflammations","complaint_category-skin-hair-and-nails"],"acf":{"short_description_title":"","short_description_content":"","tabs":[{"title":"What is impetigo?","content":"<p>There will be all kinds of wounds and infections on the skin if you or your child is suffering from impetigo. These are usually on the nose, chin, or around the mouth, but they can develop anywhere on the body. The wounds look a bit like currants. Children under the age of 12 are more likely to suffer from it, but adults can also be susceptible to it. Impetigo is caused by the staphylococcus bacteria. You or your child can be a carrier, but in most cases you won\u2019t know anything about it. You or your child will also be able to transfer the bacteria to someone else. This usually happens through touch, sneezing or coughing. Impetigo is very contagious if the wounds have not dried up yet. That\u2019s why several members of one family, group or class will often suffer from it.<\/p>\n"},{"title":"Which symptoms can I expect with impetigo?","content":"<p>Impetigo will result in you or your child suffering from the following symptoms:<\/p>\n<ul>\n<li>A scrape, wound or eczema spot on your skin. Impetigo often develops where there\u2019s damage already.<\/li>\n<li>Merging red spots, wounds and blisters. Yellow pus will often come out of the wounds and blisters.<\/li>\n<li>Yellow-brown scabs on the wounds and blisters which have dried up.<\/li>\n<li>Itching.<\/li>\n<li>Swollen glands in the neck when the impetigo is on the face.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n"},{"title":"What can I do about impetigo myself?","content":"<p>There are a number of things you can do to minimise the spread of the bacteria to others and reduce impetigo. For example, we recommend that you:<\/p>\n<ul>\n<li>Leave your skin, wounds and infections alone. Don\u2019t scratch it and avoid picking at it.<\/li>\n<li>Thoroughly wash your hands several times a day. Thoroughly dry your hands afterwards.<\/li>\n<li>Wash yourself or your child well with soap. Thoroughly dry yourself and make sure your nails are trimmed. This prevents the bacteria from getting under the nails.<\/li>\n<li>Inform your family members, group members or your child&#8217;s classmates. They should also regularly wash their hands to prevent any possible spread.<\/li>\n<li>Thoroughly clean and maintain your home. For example, regularly give your door handles or banisters an extra clean.<\/li>\n<\/ul>\n<p>It\u2019s not necessary to use special disinfectants. These work no better than soap and are often more expensive.<\/p>\n"},{"title":"When should I go and see the doctor for impetigo?","content":"<p>You should visit your GP if you suspect you or your child have impetigo. Your GP can then prescribe a fusidic acid cream or a course of antibiotics. These will ensure the impetigo heals faster. We would also recommend visiting your GP if you or your child suffer from it regularly or for a long time.<\/p>\n"}],"original_post_id":"2_73","disable_sync":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impetigo - Huisartsenposten Amsterdam - English<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impetigo - Huisartsenposten Amsterdam - English\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Huisartsenposten Amsterdam - English\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/health-complaints\\\/impetigo\\\/\",\"url\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/health-complaints\\\/impetigo\\\/\",\"name\":\"Impetigo - Huisartsenposten Amsterdam - English\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/#website\"},\"datePublished\":\"2025-05-26T11:33:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/health-complaints\\\/impetigo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/health-complaints\\\/impetigo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/health-complaints\\\/impetigo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Health complaints\",\"item\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/health-complaints\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impetigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/\",\"name\":\"Huisartsenposten Amsterdam - English\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impetigo - Huisartsenposten Amsterdam - English","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/","og_locale":"en_US","og_type":"article","og_title":"Impetigo - Huisartsenposten Amsterdam - English","og_url":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/","og_site_name":"Huisartsenposten Amsterdam - English","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/","url":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/","name":"Impetigo - Huisartsenposten Amsterdam - English","isPartOf":{"@id":"https:\/\/huisartsenpostenamsterdam.nl\/en\/#website"},"datePublished":"2025-05-26T11:33:52+00:00","breadcrumb":{"@id":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/impetigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huisartsenpostenamsterdam.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Health complaints","item":"https:\/\/huisartsenpostenamsterdam.nl\/en\/health-complaints\/"},{"@type":"ListItem","position":3,"name":"Impetigo"}]},{"@type":"WebSite","@id":"https:\/\/huisartsenpostenamsterdam.nl\/en\/#website","url":"https:\/\/huisartsenpostenamsterdam.nl\/en\/","name":"Huisartsenposten Amsterdam - English","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huisartsenpostenamsterdam.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/complaint\/53059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/complaint"}],"about":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/types\/complaint"}],"wp:attachment":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/media?parent=53059"}],"wp:term":[{"taxonomy":"complaint_tag","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/complaint_tag?post=53059"},{"taxonomy":"complaint_body_part","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/complaint_body_part?post=53059"},{"taxonomy":"complaint_age_group","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/complaint_age_group?post=53059"},{"taxonomy":"complaint_category","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/en\/wp-json\/wp\/v2\/complaint_category?post=53059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}