{"id":53211,"date":"2025-05-26T14:54:54","date_gmt":"2025-05-26T12:54:54","guid":{"rendered":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/"},"modified":"2025-12-13T09:18:44","modified_gmt":"2025-12-13T08:18:44","slug":"%d8%ac%d8%b1%d8%ad","status":"publish","type":"complaint","link":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/","title":{"rendered":"\u062c\u0631\u062d"},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[]},"complaint_tag":[],"complaint_body_part":[],"complaint_age_group":[],"complaint_category":[],"class_list":["post-53211","complaint","type-complaint","status-publish","hentry"],"acf":{"short_description_title":"\u0628\u0627\u062e\u062a\u0635\u0627\u0631","short_description_content":"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c <a href=\"https:\/\/www.moetiknaardedokter.nl\/klacht\/bijtwond\/\">\u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c<\/a> \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c <a href=\"https:\/\/moetiknaardedokter.nl\/klacht\/brandwond\/\">\u0648\u0627\u0644\u062d\u0631\u0648\u0642.<\/a> \u0627\u0639\u062a\u0645\u0627\u062f\u0627 \u0639\u0644\u0649 \u0646\u0648\u0639 \u0627\u0644\u062c\u0631\u062d\u060c \u0642\u062f \u062a\u0648\u0627\u062c\u0647 \u0634\u0643\u0627\u0648\u0649 \u0625\u0636\u0627\u0641\u064a\u0629.","tabs":[{"title":"\u0645\u0627 \u0647\u064a \u0627\u0644\u062c\u0631\u0648\u062d\u061f","content":"<p>\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u062e\u062f\u0634 \u060c \u064a\u062a\u0645 \u0635\u0646\u0641\u0631\u0629 \u0627\u0644\u062c\u0644\u062f \u0648\u0641\u062a\u062d\u0647\u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644 \u0644\u0623\u0646\u0643 \u0633\u0642\u0637\u062a \u0639\u0644\u0649 \u0627\u0644\u0634\u0627\u0631\u0639. \u0645\u0639 \u062c\u0631\u062d \u0627\u0644\u0639\u0636\u0629\u060c \u062a\u0643\u0648\u0646 \u0642\u062f \u0639\u0636\u0643 \u0623\u0648 \u0625\u0646\u0633\u0627\u0646 \u0648\u062a\u0645 \u062a\u062f\u0645\u064a\u0631 \u062c\u0644\u062f\u0643. \u0627\u0644\u062c\u0631\u062d \u064a\u062d\u062f\u062b \u0639\u0646\u062f\u0645\u0627 \u062a\u0642\u0637\u0639 \u0646\u0641\u0633\u0643 \u0628\u062c\u0633\u0645 \u062d\u0627\u062f \u0645\u062b\u0644 \u0633\u0643\u064a\u0646 \u0623\u0648 \u0639\u0644\u0628\u0629. \u063a\u0627\u0644\u0628\u0627 \u0645\u0627 \u064a\u062d\u062f\u062b \u0627\u0644\u062a\u0645\u0632\u0642 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0642\u062a\u0627\u0644 \u0623\u0648 \u0623\u062b\u0646\u0627\u0621 \u0645\u0645\u0627\u0631\u0633\u0629 \u0628\u0639\u0636 \u0627\u0644\u0631\u064a\u0627\u0636\u0627\u062a\u060c \u0648\u064a\u062d\u062f\u062b \u0627\u0644\u062d\u0631\u0642 \u0628\u0639\u062f \u062d\u0631\u0642 \u0627\u0644\u062c\u0644\u062f.<\/p>\n"},{"title":"\u0645\u0627 \u0647\u064a \u0627\u0644\u0634\u0643\u0627\u0648\u0649 \u0627\u0644\u062a\u064a \u0644\u062f\u064a \u0645\u0646 \u0627\u0644\u062c\u0631\u0648\u062d\u061f","content":"<p>\u0645\u0639 \u0627\u0644\u0643\u0634\u0637 \u0633\u062a\u0648\u0627\u062c\u0647 \u0627\u0644\u0634\u0643\u0627\u0648\u0649 \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n<ul>\n<li>\u0642\u062f \u064a\u0624\u0644\u0645\u0647 \u0627\u0644\u062c\u0631\u062d \u0623\u0648 \u064a\u062d\u0631\u0642\u060c \u0648\u0647\u0648 \u0645\u0627 \u062a\u0634\u0639\u0631 \u0628\u0647 \u0645\u0624\u0644\u0645\u0627<\/li>\n<li>\u0628\u0634\u0631\u062a\u0643 \u062a\u0636\u0631\u0631\u062a \u0648\u062a\u0631\u0649 \u0646\u0642\u0627\u0637\u0627 \u062d\u0645\u0631\u0627\u0621 \u0639\u0644\u0649 \u0627\u0644\u062c\u0644\u062f \u0627\u0644\u0645\u062e\u062f\u0648\u0634<\/li>\n<li>\u0648\u0628\u0645\u0627 \u0623\u0646 \u0627\u0644\u062c\u0631\u062d \u0645\u0641\u062a\u0648\u062d\u060c \u0642\u062f \u064a\u062a\u0643\u0648\u0646 \u0628\u0639\u0636 \u0633\u0627\u0626\u0644 \u0627\u0644\u062c\u0631\u062d. \u0633\u064a\u0628\u062f\u0648 \u0647\u0630\u0627 \u0627\u0644\u0644\u0648\u0646 \u0623\u0635\u0641\u0631 \u0648\u0642\u062f \u064a\u062c\u0641 \u0644\u064a\u0635\u0628\u062d \u0642\u0634\u0631\u0629.<\/li>\n<\/ul>\n<p>\u0645\u0639 \u0627\u0644\u062c\u0631\u062d\u060c \u0633\u062a\u0648\u0627\u062c\u0647 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n<ul>\n<li>\u0627\u0644\u062c\u0631\u062d \u0644\u0647 \u062d\u0648\u0627\u0641 \u062d\u0627\u062f\u0629<\/li>\n<li>\u0642\u062f \u064a\u0643\u0648\u0646 \u0627\u0644\u062c\u0631\u062d \u0639\u0645\u064a\u0642\u0627 \u0648\u064a\u0646\u0632\u0641 \u0628\u0643\u062b\u0627\u0641\u0629<\/li>\n<\/ul>\n<p>\u0645\u0639 \u0627\u0644\u062a\u0645\u0632\u0642 \u0633\u062a\u0648\u0627\u062c\u0647 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n<ul>\n<li>\u0627\u0644\u062c\u0631\u062d \u0644\u064a\u0633 \u0639\u0645\u064a\u0642\u0627 \u0648\u0644\u0647 \u062d\u0627\u0641\u0629 \u063a\u064a\u0631 \u0645\u0646\u062a\u0638\u0645\u0629<\/li>\n<li>\u0642\u0637\u0639 \u0627\u0644\u062c\u0644\u062f \u0627\u0646\u0632\u0644\u0642\u062a<\/li>\n<\/ul>\n<p>\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u062d\u0631\u0648\u0642 \u060c \u064a\u0645\u0643\u0646 \u0627\u0644\u062a\u0645\u064a\u064a\u0632 \u0628\u064a\u0646 \u0623\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u0629 \u062d\u0633\u0628 \u0634\u062f\u0629 \u0627\u0644\u062d\u0631\u0648\u0642:<\/p>\n<ul>\n<li>\u0627\u0644\u062d\u0631\u0642 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0647\u0648 \u0628\u0642\u0639\u0629 \u062d\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0644\u0645. \u0623\u062d\u064a\u0627\u0646\u0627 \u064a\u0646\u062a\u0641\u062e \u0627\u0644\u062c\u0644\u062f. \u0645\u062b\u0627\u0644 \u0639\u0644\u0649 \u0630\u0644\u0643\u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u060c \u0647\u0648 \u062d\u0631\u0642 \u0627\u0644\u062c\u0644\u062f \u0628\u0639\u062f \u0627\u0644\u062c\u0644\u0648\u0633 \u062a\u062d\u062a \u0627\u0644\u0634\u0645\u0633 \u0644\u0641\u062a\u0631\u0629 \u0637\u0648\u064a\u0644\u0629.<\/li>\n<li>\u0627\u0644\u062d\u0631\u0642 \u0627\u0644\u0633\u0637\u062d\u064a \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 \u064a\u0643\u0648\u0646 \u0623\u064a\u0636\u0627 \u0623\u062d\u0645\u0631 \u0648\u0645\u0624\u0644\u0645\u060c \u0644\u0643\u0646 \u0627\u0644\u062c\u0644\u062f \u0623\u064a\u0636\u0627 \u0645\u062a\u0636\u0631\u0631 \u0628\u0634\u0643\u0644 \u0648\u0627\u0636\u062d. \u0627\u0644\u062c\u0631\u062d \u0631\u0637\u0628\u060c \u0645\u0645\u0627 \u064a\u0639\u0646\u064a \u0623\u0646 \u0628\u062b\u0631\u0629 \u0633\u062a\u062a\u0643\u0648\u0646.<\/li>\n<li>\u0641\u064a \u0627\u0644\u062d\u0631\u0642 \u0627\u0644\u0639\u0645\u064a\u0642 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0646\u064a\u0629\u060c \u064a\u0643\u0648\u0646 \u0627\u0644\u062c\u0644\u062f \u0623\u064a\u0636\u0627 \u0645\u062a\u0636\u0631\u0631\u0627 \u0628\u0634\u0643\u0644 \u0648\u0627\u0636\u062d. \u064a\u062a\u062d\u0648\u0644 \u0627\u0644\u062c\u0644\u062f \u0625\u0644\u0649 \u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 \u0648\u064a\u0624\u0644\u0645\u0647 \u0643\u062b\u064a\u0631\u0627. \u062a\u0638\u0647\u0631 \u0627\u0644\u0628\u062b\u0648\u0631 \u0623\u064a\u0636\u0627 \u0647\u0646\u0627.<\/li>\n<li>\u0627\u0644\u062d\u0631\u0642 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0644\u062b\u0629 \u0647\u0648 \u062c\u0631\u062d \u0623\u0628\u064a\u0636 \u0623\u0648 \u0623\u0633\u0648\u062f. \u0644\u0623\u0646 \u0627\u0644\u0623\u0639\u0635\u0627\u0628 \u0641\u064a \u062c\u0644\u062f\u0643 \u0645\u062d\u062a\u0631\u0642\u0629\u060c \u0628\u0627\u0644\u0643\u0627\u062f \u062a\u0634\u0639\u0631 \u0628\u0623\u064a \u0623\u0644\u0645. \u0627\u0644\u062c\u0644\u062f \u064a\u0628\u062f\u0648 \u0643\u0646\u0648\u0639 \u0645\u0646 \u0627\u0644\u062c\u0644\u062f.<\/li>\n<\/ul>\n"},{"title":"\u0645\u0627\u0630\u0627 \u064a\u0645\u0643\u0646\u0646\u064a \u0623\u0646 \u0623\u0641\u0639\u0644 \u0641\u064a \u062d\u0627\u0644 \u062d\u062f\u0648\u062b \u062c\u0631\u0648\u062d\u061f","content":"<p>\u0641\u064a \u062d\u0627\u0644\u0629 \u062d\u062f\u0648\u062b \u062e\u062f\u0634:<\/p>\n<ul>\n<li>\u062a\u0623\u0643\u062f \u0645\u0646 \u0634\u0637\u0641 \u0627\u0644\u062c\u0631\u062d \u0628\u0645\u0627\u0621 \u0641\u0627\u062a\u0631 \u0645\u0646 \u0627\u0644\u062f\u0634 \u0623\u0648 \u0627\u0644\u0635\u0646\u0628\u0648\u0631. \u062a\u062c\u0646\u0628 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0635\u0627\u0628\u0648\u0646 \u0623\u0648 \u0627\u0644\u0645\u0637\u0647\u0631. \u0627\u0634\u0637\u0641 \u062d\u0628\u0627\u062a \u0627\u0644\u0631\u0645\u0644 \u0623\u0648 \u0623\u064a \u0623\u0648\u0633\u0627\u062e \u0623\u062e\u0631\u0649 \u0628\u0628\u0626\u0631 \u062c\u064a\u062f. \u0625\u0630\u0627 \u0644\u0645 \u064a\u0646\u062c\u062d \u0627\u0644\u0623\u0645\u0631\u060c \u064a\u0645\u0643\u0646\u0643 \u0645\u062d\u0627\u0648\u0644\u0629 \u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0642\u0637\u0639 \u0627\u0644\u0643\u0628\u064a\u0631\u0629 \u0645\u0646 \u0627\u0644\u0623\u0648\u0633\u0627\u062e \u0628\u0645\u0644\u0642\u0637 \u0628\u0639\u0646\u0627\u064a\u0629.<\/li>\n<li>\u062f\u0639 \u0627\u0644\u062c\u0631\u062d \u064a\u062c\u0641 \u062f\u0648\u0646 \u062a\u063a\u0637\u064a\u062a\u0647\u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u060c \u0628\u0627\u0644\u062c\u0628\u0633. \u0647\u0630\u0627 \u064a\u062e\u0644\u0642 \u0642\u0634\u0631\u0629 \u0642\u0634\u0631\u0629. \u0625\u0630\u0627 \u0643\u0627\u0646 \u0644\u062f\u064a\u0643 \u062e\u062f\u0634 \u0623\u0639\u0645\u0642 \u0623\u0648 \u062e\u062f\u0634 \u064a\u062d\u062a\u0643 \u0628\u0645\u0644\u0627\u0628\u0633\u0643\u060c \u0641\u0645\u0646 \u0627\u0644\u0623\u0641\u0636\u0644 \u062a\u063a\u0637\u064a\u062a\u0647. \u0627\u0633\u062a\u0628\u062f\u0644 \u0627\u0644\u062c\u0628\u0633 \u0645\u0631\u062a\u064a\u0646 \u0641\u064a \u0627\u0644\u064a\u0648\u0645.<\/li>\n<\/ul>\n<p>\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u062c\u0631\u062d \u0623\u0648 \u0627\u0644\u062c\u0631\u062d:<\/p>\n<ul>\n<li>\u062a\u0623\u0643\u062f \u0645\u0646 \u0623\u0646\u0647 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0627\u0644\u062c\u0631\u062d \u064a\u0646\u0632\u0641 \u0642\u0644\u064a\u0644\u0627\u060c \u0627\u0634\u0637\u0641\u0647\u0627 \u0628\u0645\u0627\u0621 \u0641\u0627\u062a\u0631 \u0645\u0646 \u0627\u0644\u062f\u0634 \u0623\u0648 \u0627\u0644\u0635\u0646\u0628\u0648\u0631. \u0647\u0630\u0627 \u064a\u0633\u0645\u062d \u0644\u0643 \u0628\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0623\u0648\u0633\u0627\u062e \u0645\u0646 \u0627\u0644\u062c\u0631\u062d. \u062a\u062c\u0646\u0628 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0635\u0627\u0628\u0648\u0646 \u0623\u0648 \u0627\u0644\u0645\u0637\u0647\u0631.<\/li>\n<li>\u062a\u0623\u0643\u062f \u0645\u0646 \u0632\u064a\u0627\u0631\u0629 \u0637\u0628\u064a\u0628\u0643 \u0644\u062a\u062d\u062f\u064a\u062f \u0645\u0627 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0627\u0644\u062c\u0631\u062d \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u062e\u064a\u0627\u0637\u0629 \u0623\u0648 \u0644\u0635\u0642<\/li>\n<li>\u0625\u0630\u0627 \u0644\u0632\u0645 \u0627\u0644\u0623\u0645\u0631\u060c \u0633\u064a\u062a\u0645 \u0625\u0639\u0637\u0627\u0624\u0643 \u062d\u0642\u0646\u0629 \u0644\u0645\u0646\u0639 \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u062a\u064a\u062a\u0627\u0646\u0648\u0633 . \u064a\u0645\u0643\u0646 \u0623\u0646 \u062a\u062d\u062f\u062b \u0647\u0630\u0647 \u0627\u0644\u0639\u062f\u0648\u0649 \u0625\u0630\u0627 \u0643\u0646\u062a \u0642\u062f \u062a\u0639\u0631\u0636\u062a \u0644\u062a\u0631\u0627\u0628 \u0627\u0644\u0634\u0627\u0631\u0639 \u0623\u0648 \u0631\u0648\u062b \u0623\u062b\u0646\u0627\u0621 \u062c\u0631\u062d\u0643.<\/li>\n<li>\u0625\u0630\u0627 \u0643\u0627\u0646 \u0627\u0644\u062c\u0631\u062d \u0645\u063a\u0644\u0642\u0627\u060c \u0641\u0644\u0627 \u062d\u0627\u062c\u0629 \u0644\u062a\u063a\u0637\u064a\u062a\u0647. \u0625\u0630\u0627 \u0627\u062d\u062a\u0643 \u0627\u0644\u062c\u0631\u062d \u0628\u0645\u0644\u0627\u0628\u0633\u0643 \u0648\u062a\u0633\u0631\u0628 \u0633\u0627\u0626\u0644 \u0627\u0644\u062c\u0631\u062d\u060c \u0641\u0645\u0646 \u0627\u0644\u0623\u0641\u0636\u0644 \u062a\u063a\u0637\u064a\u0629 \u0627\u0644\u062c\u0631\u062d.<\/li>\n<li>\u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0628\u0627\u0631\u0627\u0633\u064a\u062a\u0627\u0645\u0648\u0644 \u0644\u0644\u0623\u0644\u0645 \u0625\u0630\u0627 \u0644\u0632\u0645 \u0627\u0644\u0623\u0645\u0631<\/li>\n<\/ul>\n<p>\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u062d\u0631\u0642:<\/p>\n<ul>\n<li>\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0627\u062d\u062a\u0631\u0627\u0642\u060c \u0627\u0644\u062a\u0628\u0631\u064a\u062f \u0627\u0644\u0645\u0628\u0627\u0634\u0631 \u062a\u062d\u062a \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u062c\u0627\u0631\u064a\u0629 \u0645\u0647\u0645 \u062c\u062f\u0627. \u0647\u0630\u0627 \u064a\u0636\u0645\u0646 \u062a\u0648\u0642\u0641 \u0627\u0644\u0627\u062d\u062a\u0631\u0627\u0642. \u0628\u0631\u062f \u0627\u0644\u062d\u0631\u0642 \u062a\u062d\u062a \u0627\u0644\u0635\u0646\u0628\u0648\u0631 \u0644\u0645\u062f\u0629 \u0644\u0627 \u062a\u0642\u0644 \u0639\u0646 \u0639\u0634\u0631 \u062f\u0642\u0627\u0626\u0642. \u0627\u0633\u062a\u062e\u062f\u0645 \u0645\u0627\u0621 \u0641\u0627\u062a\u0631 \u0648\u0646\u0627\u0639\u0645 \u0627\u0644\u062c\u0631\u064a. \u0625\u0630\u0627 \u0627\u0633\u062a\u062e\u062f\u0645\u062a \u0645\u0627\u0621 \u0645\u062b\u0644\u062c\u060c \u0642\u062f \u064a\u0624\u0644\u0645 \u0627\u0644\u062c\u0631\u062d \u0623\u0643\u062b\u0631 \u0623\u0648 \u0633\u062a\u0635\u0627\u0628 \u0628\u0627\u0646\u062e\u0641\u0627\u0636 \u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u062c\u0633\u0645. \u0625\u0630\u0627 \u0644\u0645 \u064a\u0643\u0646 \u0647\u0646\u0627\u0643 \u0625\u0645\u0643\u0627\u0646\u064a\u0629 \u0644\u062a\u0634\u063a\u064a\u0644 \u0627\u0644\u0645\u064a\u0627\u0647 \u0627\u0644\u062c\u0627\u0631\u064a\u0629\u060c \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0623\u0642\u0645\u0634\u0629 \u0645\u0628\u0644\u0644\u0629. \u0625\u0630\u0627 \u0644\u0645 \u064a\u0643\u0646 \u0647\u0630\u0627 \u0645\u0648\u062c\u0648\u062f\u0627\u060c \u0641\u0625\u0646 \u0627\u0644\u063a\u0645\u0631 \u0641\u064a \u0646\u0648\u0639 \u0645\u062e\u062a\u0644\u0641 \u0645\u0646 \u0627\u0644\u0645\u0627\u0621 \u0623\u0641\u0636\u0644 \u0645\u0646 \u0644\u0627 \u0634\u064a\u0621.<\/li>\n<li>\u0625\u0630\u0627 \u0623\u0645\u0643\u0646\u060c \u0642\u0645 \u0628\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0645\u0644\u0627\u0628\u0633 \u0644\u0643\u0646 \u0627\u062a\u0631\u0643 \u0623\u064a \u0645\u0644\u0627\u0628\u0633 \u062a\u0644\u062a\u0635\u0642 \u0628\u0627\u0644\u062d\u0631\u0642 . \u0625\u0630\u0627 \u062e\u0644\u0639\u062a \u0647\u0630\u0647 \u0627\u0644\u0645\u0644\u0627\u0628\u0633\u060c \u0633\u062a\u062a\u0644\u0641 \u0627\u0644\u0628\u0634\u0631\u0629.<\/li>\n<li>\u0644\u0627 \u062a\u0636\u0639 \u0627\u0644\u0645\u0631\u0647\u0645 \u0639\u0644\u0649 \u0627\u0644\u062c\u0631\u062d \u0623\u0648 \u062a\u0644\u0645\u0633 \u0627\u0644\u062c\u0631\u062d.<\/li>\n<li>\u062a\u063a\u0637\u064a\u0629 \u0627\u0644\u062d\u0631\u0642 \u0644\u064a\u0633\u062a \u0636\u0631\u0648\u0631\u064a\u0629. \u0627\u0641\u062a\u0631\u0636 \u0623\u0646 \u0628\u062b\u0648\u0631 \u0638\u0647\u0631\u062a \u0639\u0644\u0649 \u0627\u0644\u062d\u0631\u0642\u060c \u064a\u0645\u0643\u0646\u0643 \u0648\u0636\u0639 \u0634\u0627\u0634 \u062f\u0647\u0646\u064a \u0639\u0644\u0649 \u0627\u0644\u062c\u0631\u062d. \u0647\u0630\u0627 \u064a\u0645\u0646\u0639 \u0627\u0644\u0623\u0648\u0633\u0627\u062e \u0645\u0646 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u062c\u0631\u062d.<\/li>\n<\/ul>\n"},{"title":"\u0645\u062a\u0649 \u064a\u062c\u0628 \u0623\u0646 \u0623\u0632\u0648\u0631 \u0627\u0644\u0637\u0628\u064a\u0628 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u062c\u0631\u0648\u062d\u061f","content":"<p>\u062a\u0648\u0627\u0635\u0644 \u0645\u0639 \u0637\u0628\u064a\u0628\u0643 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0644\u062f\u064a\u0643 \u062e\u062f\u0634 \u0641\u064a \u0627\u0644\u062d\u0627\u0644\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n<ul>\n<li>\u0644\u0627 \u064a\u0645\u0643\u0646 \u0625\u062c\u0631\u0627\u0621 \u062d\u0631\u0643\u0627\u062a \u0645\u0639\u064a\u0646\u0629 \u0639\u0628\u0631 \u0627\u0644\u062c\u0631\u062d<\/li>\n<li>\u0623\u0646\u062a \u0642\u0644\u0642 \u0628\u0634\u0623\u0646 \u0627\u0644\u062e\u062f\u0634<\/li>\n<li>\u0627\u0644\u062c\u0631\u062d \u064a\u0646\u0632\u0641 \u0643\u062b\u064a\u0631\u0627 \u0648\u0644\u0641\u062a\u0631\u0629 \u0637\u0648\u064a\u0644\u0629<\/li>\n<li>\u064a\u0628\u062f\u0623 \u0627\u0644\u062c\u0631\u062d \u0628\u0627\u0644\u062a\u0633\u0631\u0628 \u0648\u064a\u0637\u0644\u0642 \u0627\u0644\u0645\u0632\u064a\u062f \u0648\u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0633\u0648\u0627\u0626\u0644<\/li>\n<li>\u0623\u0646\u062a \u062a\u062a\u0623\u0644\u0645 \u0643\u062b\u064a\u0631\u0627 \u0628\u0633\u0628\u0628 \u0627\u0644\u062e\u062f\u0634<\/li>\n<li>\u0643\u0627\u0646 \u0627\u0644\u0643\u0634\u062d \u0639\u0644\u0649 \u0627\u062a\u0635\u0627\u0644 \u0628\u062a\u0631\u0627\u0628 \u0627\u0644\u0634\u0648\u0627\u0631\u0639\u060c \u0623\u0648 \u0627\u0644\u0631\u0648\u062b\u060c \u0623\u0648 \u0634\u062e\u0635 \u0645\u0635\u0627\u0628 \u0628\u0641\u064a\u0631\u0648\u0633 \u0646\u0642\u0635 \u0627\u0644\u0645\u0646\u0627\u0639\u0629 \u0627\u0644\u0628\u0634\u0631\u064a\u0629\u060c \u0623\u0648 \u0627\u0644\u062a\u0647\u0627\u0628 \u0627\u0644\u0643\u0628\u062f \u0627\u0644\u0648\u0628\u0627\u0626\u064a C \u060c \u0623\u0648 \u0645\u0635\u0627\u0628 \u0628\u062f\u0627\u0621<\/li>\n<\/ul>\n<p>\u0641\u064a \u0627\u0644\u0623\u064a\u0627\u0645 \u0627\u0644\u0642\u0644\u064a\u0644\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0628\u0639\u062f \u062d\u062f\u0648\u062b \u0627\u0644\u062e\u062f\u0648\u0634 \u060c \u0631\u0627\u062c\u0639 \u0637\u0628\u064a\u0628\u0643:<\/p>\n<ul>\n<li>\u0625\u0630\u0627 \u0638\u0647\u0631\u062a \u0639\u062f\u0648\u0649 . \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062e\u0631\u0648\u062c \u0633\u0627\u0626\u0644 \u0627\u0644\u062c\u0631\u062d \u0645\u0646 \u0627\u0644\u062c\u0631\u062d\u060c \u0623\u0648 \u0623\u0646 \u0627\u0644\u062c\u0631\u062d \u0633\u064a\u0624\u0644\u0645 \u0623\u0643\u062b\u0631 \u0623\u0648 \u0623\u0646\u0643 \u0633\u062a\u0635\u0627\u0628 \u0628\u062d\u0645\u0649.<\/li>\n<li>\u0639\u0646\u062f\u0645\u0627 \u0644\u0627 \u064a\u0628\u062f\u0648 \u0627\u0644\u062c\u0631\u062d \u0623\u0641\u0636\u0644 \u0628\u0639\u062f \u064a\u0648\u0645\u064a\u0646<\/li>\n<\/ul>\n<p>\u0627\u062a\u0635\u0644 \u0628\u0627\u0644\u0631\u0642\u0645 112 \u0641\u064a \u062d\u0627\u0644 \u062d\u062f\u0648\u062b \u062c\u0631\u062d \u0623\u0648 \u062c\u0631\u062d:<\/p>\n<ul>\n<li>\u0639\u0646\u062f\u0645\u0627 \u064a\u0635\u0627\u0628 \u0634\u062e\u0635 \u0645\u0627 \u0628\u062c\u0631\u062d \u0637\u0639\u0646\u0629 \u0648\u064a\u062a\u062d\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0631\u0645\u0627\u062f\u064a \u0623\u0648 \u0627\u0644\u0645\u062a\u0639\u0631\u0642 \u0623\u0648 \u0627\u0644\u062a\u0648\u062a\u0631<\/li>\n<li>\u0639\u0646\u062f\u0645\u0627 \u064a\u0635\u0628\u062d \u0634\u062e\u0635 \u0645\u062a\u0639\u0631\u0636 \u0644\u062c\u0631\u062d \u0623\u0648 \u062a\u0645\u0632\u0642 \u0646\u0639\u0633\u0627\u0646\u0627 \u0623\u0648 \u0641\u0627\u0642\u062f\u0627 \u0644\u0644\u0648\u0639\u064a<\/li>\n<li>\u0639\u0646\u062f\u0645\u0627 \u064a\u0646\u0632\u0641 \u0627\u0644\u062c\u0631\u062d \u0643\u062b\u064a\u0631\u0627 \u0644\u062f\u0631\u062c\u0629 \u0623\u0646\u0647 \u064a\u0646\u062f\u0641\u0639 \u0627\u0644\u062f\u0645 \u0645\u0646 \u0627\u0644\u062c\u0631\u062d<\/li>\n<\/ul>\n<p>\u0627\u062a\u0635\u0644 \u0628\u0633\u0631\u0639\u0629 \u0628\u0637\u0628\u064a\u0628 \u0627\u0644\u0639\u0627\u0645 \u0623\u0648 \u0645\u0643\u062a\u0628 \u0627\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0639\u0627\u0645 \u0641\u064a \u062d\u0627\u0644 \u0648\u062c\u0648\u062f \u062c\u0631\u062d \u0623\u0648 \u062a\u0645\u0632\u0642:<\/p>\n<ul>\n<li>\u0625\u0630\u0627 \u0638\u0647\u0631\u062a \u0623\u0637\u0631\u0627\u0641 \u0634\u0627\u062d\u0628\u0629 \u0623\u0648 \u0628\u0627\u0631\u062f\u0629 \u0628\u0639\u062f \u0625\u0635\u0627\u0628\u0629 \u0627\u0644\u062c\u0631\u062d \u0648\u0644\u0645 \u062a\u0639\u062f \u062a\u0633\u062a\u0637\u064a\u0639 \u062a\u062d\u0631\u064a\u0643 \u0627\u0644\u0623\u0637\u0631\u0627\u0641<\/li>\n<\/ul>\n<p>\u062a\u0648\u0627\u0635\u0644 \u0645\u0639 \u0637\u0628\u064a\u0628\u0643 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0644\u062f\u064a\u0643 \u062c\u0631\u062d \u0623\u0648 \u062a\u0645\u0632\u0642 \u0641\u064a \u0627\u0644\u062d\u0627\u0644\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n<ul>\n<li>\u0625\u0630\u0627 \u0643\u0627\u0646 \u0644\u062f\u064a\u0643 \u062c\u0631\u062d \u0639\u0645\u064a\u0642 \u0623\u0648 \u0637\u0639\u0646\u0629 \u0623\u0643\u0628\u0631 \u0645\u0646 \u0633\u0646\u062a\u064a\u0645\u062a\u0631 \u0648\u0627\u062d\u062f \u0648\u062d\u0648\u0627\u0641 \u0627\u0644\u062c\u0631\u062d \u0645\u062a\u0628\u0627\u0639\u062f\u0629.<\/li>\n<li>\u0625\u0630\u0627 \u0627\u0633\u062a\u0645\u0631 \u0627\u0644\u062c\u0631\u062d \u0641\u064a \u0627\u0644\u0646\u0632\u064a\u0641<\/li>\n<li>\u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0639\u0627\u0646\u064a \u0645\u0646 \u0623\u0644\u0645 \u0634\u062f\u064a\u062f<\/li>\n<li>\u0625\u0630\u0627 \u0644\u0645 \u064a\u0643\u0646 \u0645\u0646 \u0627\u0644\u0645\u0645\u0643\u0646 \u0625\u062c\u0631\u0627\u0621 \u062d\u0631\u0643\u0627\u062a \u0645\u0639\u064a\u0646\u0629 \u0639\u0628\u0631 \u0627\u0644\u062c\u0631\u062d<\/li>\n<li>\u0625\u0630\u0627 \u0643\u0627\u0646 \u062c\u0631\u062d\u0643 \u0623\u0648 \u062a\u0645\u0632\u0642\u0643 \u0642\u062f \u0644\u0627\u0645\u0633 \u0627\u0644\u0623\u0648\u0633\u0627\u062e \u0641\u064a \u0627\u0644\u0634\u0627\u0631\u0639 \u0623\u0648 \u0645\u0639 \u0634\u062e\u0635 \u0645\u0635\u0627\u0628 \u0628\u0641\u064a\u0631\u0648\u0633 \u0646\u0642\u0635 \u0627\u0644\u0645\u0646\u0627\u0639\u0629 \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u0623\u0648 \u0627\u0644\u062a\u0647\u0627\u0628 \u0627\u0644\u0643\u0628\u062f B \u0623\u0648 C<\/li>\n<li>\u0625\u0630\u0627 \u0643\u0646\u062a \u0642\u0644\u0642\u0627<\/li>\n<\/ul>\n<p>\u0641\u064a \u0627\u0644\u0623\u064a\u0627\u0645 \u0627\u0644\u0623\u0648\u0644\u0649 \u0628\u0639\u062f \u062d\u062f\u0648\u062b \u0627\u0644\u062c\u0631\u062d \u0623\u0648 \u0627\u0644\u062c\u0631\u062d \u0627\u0644\u0646\u0627\u062a\u062c \u0639\u0646 \u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0627\u0630\u0647\u0628 \u0625\u0644\u0649 \u0637\u0628\u064a\u0628\u0643:<\/p>\n<ul>\n<li>\u0625\u0630\u0627 \u0638\u0647\u0631\u062a \u0639\u062f\u0648\u0649 . \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062e\u0631\u0648\u062c \u0633\u0627\u0626\u0644 \u0627\u0644\u062c\u0631\u062d \u0645\u0646 \u0627\u0644\u062c\u0631\u062d\u060c \u0648\u0623\u0646 \u0627\u0644\u062c\u0631\u062d \u0633\u064a\u0624\u0644\u0645\u0647 \u0623\u0643\u062b\u0631 \u0648\u0623\u0646\u0643 \u0633\u062a\u0635\u0627\u0628 \u0628\u062d\u0645\u0649.<\/li>\n<li>\u0639\u0646\u062f\u0645\u0627 \u0644\u0627 \u064a\u0628\u062f\u0648 \u0627\u0644\u062c\u0631\u062d \u0623\u0641\u0636\u0644 \u0628\u0639\u062f \u064a\u0648\u0645\u064a\u0646<\/li>\n<\/ul>\n<p>\u0627\u062a\u0635\u0644 \u0628\u0637\u0628\u064a\u0628\u0643 \u0641\u064a \u062d\u0627\u0644 \u062d\u062f\u0648\u062b \u062d\u0631\u0648\u0642 \u0625\u0630\u0627:<\/p>\n<ul>\n<li>\u0644\u0642\u062f \u062a\u0639\u0631\u0636\u062a \u0644\u062d\u0631\u0642 \u0633\u0637\u062d\u064a \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0646\u064a\u0629<\/li>\n<li>\u0644\u0642\u062f \u062a\u0639\u0631\u0636\u062a \u0644\u062d\u0631\u0642 \u0639\u0645\u064a\u0642 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0646\u064a\u0629<\/li>\n<li>\u0644\u0642\u062f \u062a\u0639\u0631\u0636\u062a \u0644\u062d\u0631\u0642 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u062b\u0627\u0644\u062b\u0629<\/li>\n<li>\u062a\u0635\u0627\u0628 \u0628\u062d\u0645\u0649 \u0648\u064a\u0635\u0628\u062d \u0627\u0644\u062c\u0631\u062d \u062f\u0627\u0641\u0626\u0627 \u0648\u0623\u062d\u0645\u0631<\/li>\n<li>\u0625\u0630\u0627 \u0644\u0645 \u064a\u0644\u062a\u0626\u0645 \u0627\u0644\u062c\u0631\u062d \u0628\u0639\u062f \u0623\u0633\u0628\u0648\u0639\u064a\u0646<\/li>\n<\/ul>\n"}],"original_post_id":"5_649","disable_sync":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062c\u0631\u062d - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a<\/title>\n<meta name=\"description\" content=\"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0639\u0644\u0627\u062c\u0647\u0627.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u062c\u0631\u062d\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062c\u0631\u062d - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\" \/>\n<meta property=\"og:description\" content=\"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0639\u0644\u0627\u062c\u0647\u0627.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u062c\u0631\u062d\/\" \/>\n<meta property=\"og:site_name\" content=\"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T08:18:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%ac%d8%b1%d8%ad\\\/\",\"url\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%ac%d8%b1%d8%ad\\\/\",\"name\":\"\u062c\u0631\u062d - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/#website\"},\"datePublished\":\"2025-05-26T12:54:54+00:00\",\"dateModified\":\"2025-12-13T08:18:44+00:00\",\"description\":\"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0639\u0644\u0627\u062c\u0647\u0627.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%ac%d8%b1%d8%ad\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%ac%d8%b1%d8%ad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%ac%d8%b1%d8%ad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0634\u0643\u0627\u0648\u0649 \u0627\u0644\u0635\u062d\u064a\u0629\",\"item\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u062c\u0631\u062d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/\",\"name\":\"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062c\u0631\u062d - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","description":"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0639\u0644\u0627\u062c\u0647\u0627.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u062c\u0631\u062d\/","og_locale":"ar_AR","og_type":"article","og_title":"\u062c\u0631\u062d - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","og_description":"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0639\u0644\u0627\u062c\u0647\u0627.","og_url":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u062c\u0631\u062d\/","og_site_name":"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","article_modified_time":"2025-12-13T08:18:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/","url":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/","name":"\u062c\u0631\u062d - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","isPartOf":{"@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/#website"},"datePublished":"2025-05-26T12:54:54+00:00","dateModified":"2025-12-13T08:18:44+00:00","description":"\u0647\u0646\u0627\u0643 \u062c\u0631\u0648\u062d \u0645\u062a\u0646\u0648\u0639\u0629\u060c \u0645\u062b\u0644 \u0627\u0644\u062e\u062f\u0648\u0634\u060c \u0648\u062c\u0631\u0648\u062d \u0627\u0644\u0639\u0636\u060c \u0648\u0627\u0644\u062c\u0631\u0648\u062d\u060c \u0648\u0627\u0644\u062a\u0645\u0632\u0642\u060c \u0648\u0627\u0644\u062d\u0631\u0648\u0642. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0639\u0644\u0627\u062c\u0647\u0627.","breadcrumb":{"@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%ac%d8%b1%d8%ad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0634\u0643\u0627\u0648\u0649 \u0627\u0644\u0635\u062d\u064a\u0629","item":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/"},{"@type":"ListItem","position":3,"name":"\u062c\u0631\u062d"}]},{"@type":"WebSite","@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/#website","url":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/","name":"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint\/53211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint"}],"about":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/types\/complaint"}],"wp:attachment":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/media?parent=53211"}],"wp:term":[{"taxonomy":"complaint_tag","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_tag?post=53211"},{"taxonomy":"complaint_body_part","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_body_part?post=53211"},{"taxonomy":"complaint_age_group","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_age_group?post=53211"},{"taxonomy":"complaint_category","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_category?post=53211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}