{"id":53160,"date":"2025-05-26T14:54:37","date_gmt":"2025-05-26T12:54:37","guid":{"rendered":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/"},"modified":"2025-05-26T14:54:37","modified_gmt":"2025-05-26T12:54:37","slug":"%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86","status":"publish","type":"complaint","link":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/","title":{"rendered":"\u0627\u0644\u0630\u0647\u0627\u0646"},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[]},"complaint_tag":[],"complaint_body_part":[],"complaint_age_group":[],"complaint_category":[],"class_list":["post-53160","complaint","type-complaint","status-publish","hentry"],"acf":{"short_description_title":"","short_description_content":"","tabs":[{"title":"\u0645\u0627 \u0647\u0648 \u0627\u0644\u0630\u0647\u0627\u0646\u061f","content":"<p>\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0646\u062a\u064a\u062c\u0629 \u0644\u0630\u0644\u0643 \u060c \u064a\u0645\u0643\u0646 \u0644\u0634\u062e\u0635 \u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0646 \u064a\u0644\u0627\u062d\u0638 \/ \u064a\u062e\u062a\u0628\u0631 \u0623\u0634\u064a\u0627\u0621 \u0644\u0627 \u064a\u0644\u0627\u062d\u0638\u0647\u0627 \u0627\u0644\u0622\u062e\u0631\u0648\u0646 \/ \u064a\u062e\u062a\u0628\u0631\u0648\u0646\u0647\u0627.<\/p>\n<p>\u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u062d\u062f\u062b \u0627\u0644\u0630\u0647\u0627\u0646 \u0628\u0633\u0628\u0628 \u062a\u062c\u0631\u0628\u0629 \u0645\u0624\u0644\u0645\u0629 \u0645\u0646\u0630 \u0627\u0644\u0637\u0641\u0648\u0644\u0629 \u060c \u0648\u0644\u0643\u0646 \u0623\u064a\u0636\u0627 \u0628\u0633\u0628\u0628 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0645\u062c\u0647\u062f\u0629. \u0623\u0638\u0647\u0631\u062a \u0627\u0644\u0623\u0628\u062d\u0627\u062b \u0623\u0646 \u062a\u0639\u0627\u0637\u064a \u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0633\u0628\u0628 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u064a\u0636\u0627. \u0641\u064a \u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u0644\u0627 \u064a\u0648\u062c\u062f \u0633\u0628\u0628 \u0645\u062d\u062f\u062f \u0644\u0634\u062e\u0635 \u0645\u0627 \u060c \u0648\u0644\u0643\u0646\u0647 \u064a\u0631\u062c\u0639 \u0625\u0644\u0649 \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0639\u0648\u0627\u0645\u0644 \u060c \u0645\u062b\u0644 \u0627\u0644\u0648\u0631\u0627\u062b\u0629 \u0623\u0648 \u0627\u0644\u0639\u062f\u0648\u0649 \u0623\u0648 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0635\u0627\u062f\u0645\u0629 \u0623\u0648 \u0627\u0644\u0625\u062c\u0647\u0627\u062f \u0623\u0648 \u062a\u0639\u0627\u0637\u064a \u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a. \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644 \u060c \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0630\u064a \u0644\u062f\u064a\u0647 \u0623\u0641\u0631\u0627\u062f \u0645\u0646 \u0627\u0644\u0639\u0627\u0626\u0644\u0629 \u062a\u0645 \u062a\u0634\u062e\u064a\u0635 \u0625\u0635\u0627\u0628\u062a\u0647\u0645 \u0628\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u062b\u0646\u0627\u0626\u064a\u0629 \u0627\u0644\u0642\u0637\u0628 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628 \u0647\u0648 \u0623\u0643\u062b\u0631 \u0639\u0631\u0636\u0629 \u0644\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0630\u0647\u0627\u0646.<\/p>\n"},{"title":"\u0645\u0627 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u062a\u064a \u0623\u0639\u0627\u0646\u064a \u0645\u0646\u0647\u0627 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646\u061f","content":"<p>\u063a\u0627\u0644\u0628\u0627 \u0645\u0627 \u062a\u0628\u062f\u0623 \u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0630\u0647\u0627\u0646 \u0628\u062a\u063a\u064a\u064a\u0631 \u0627\u0644\u0633\u0644\u0648\u0643 \u060c \u0648\u0639\u0632\u0644 \u0646\u0641\u0633\u0643 \u0639\u0646 \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0648\u062a\u0635\u0628\u062d \u0623\u0642\u0644 \u0646\u0634\u0627\u0637\u0627. \u062a\u062e\u062a\u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0623\u062d\u064a\u0627\u0646\u0627 \u0645\u0646 \u062a\u0644\u0642\u0627\u0621 \u0646\u0641\u0633\u0647\u0627 \u0648\u0644\u0627 \u062a\u0639\u0646\u064a \u0628\u0627\u0644\u0636\u0631\u0648\u0631\u0629 \u0623\u0646 \u0647\u0630\u0647 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0633\u062a\u062a\u062d\u0648\u0644 \u0625\u0644\u0649 \u0630\u0647\u0627\u0646. \u0641\u064a \u0628\u062f\u0627\u064a\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u062a\u062d\u062f\u062b \u0623\u0639\u0631\u0627\u0636 \u0645\u062b\u0644:<\/p>\n<ul>\n<li>\u062e\u0648\u0641.<\/li>\n<li>\u0627\u0644\u0646\u0648\u0645.<\/li>\n<li>\u0627\u0644\u0642\u0644\u064a\u0644 \u0645\u0646 \u0627\u0644\u062f\u0627\u0641\u0639.<\/li>\n<li>\u0627\u0644\u0639\u0632\u0644\u0629 \u0639\u0646 \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a.<\/li>\n<li>\u0625\u062f\u0631\u0627\u0643 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u062a\u064a \u0644\u0627 \u064a\u0644\u0627\u062d\u0638\u0647\u0627 \u0627\u0644\u0622\u062e\u0631\u0648\u0646.<\/li>\n<li>\u0623\u0646 \u062a\u0643\u0648\u0646 \u0645\u0634\u0628\u0648\u0647\u0627.<\/li>\n<li>\u0627\u0647\u062a\u0645\u0627\u0645 \u0623\u0648 \u062a\u0631\u0643\u064a\u0632 \u0623\u0642\u0644.<\/li>\n<li>\u0633\u0648\u0621 \u0627\u0644\u062a\u0641\u0643\u064a\u0631.<\/li>\n<\/ul>\n<p>\u0625\u0630\u0627 \u062a\u062d\u0648\u0644\u062a \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0625\u0644\u0649 \u0630\u0647\u0627\u0646 \u060c \u0641\u0647\u0646\u0627\u0643 \u062b\u0644\u0627\u062b\u0629 \u0623\u0639\u0631\u0627\u0636 \u0623\u0643\u062b\u0631 \u0645\u0627 \u064a\u0645\u064a\u0632 \u0627\u0644\u0630\u0647\u0627\u0646:<\/p>\n<ul>\n<li>\u0627\u0644\u0627\u0648\u0647\u0627\u0645. \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u062d\u0627\u0644\u0629 \u060c \u0644\u062f\u0649 \u0634\u062e\u0635 \u0645\u0627 \u0623\u0641\u0643\u0627\u0631 \u0623\u0648 \u0648\u062c\u0647\u0627\u062a \u0646\u0638\u0631 \u0644\u0627 \u062a\u062a\u0646\u0627\u0633\u0628 \u0645\u0639 \u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0623\u0648 \u0627\u0644\u0622\u0631\u0627\u0621 &#8220;\u0627\u0644\u0639\u0627\u062f\u064a\u0629&#8221;. \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644 \u060c \u0642\u062f \u064a\u0639\u062a\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0623\u0646 \u0647\u0630\u0627 \u0627\u0644\u0634\u062e\u0635 \u064a\u0637\u0627\u0631\u062f \u060c \u0641\u064a \u062d\u064a\u0646 \u0623\u0646 \u0647\u0630\u0627 \u0644\u064a\u0633 \u0647\u0648 \u0627\u0644\u062d\u0627\u0644.<\/li>\n<li>\u0627\u0644\u0647\u0644\u0648\u0633\u0647. \u064a\u062a\u0636\u0645\u0646 \u0630\u0644\u0643 \u0633\u0645\u0627\u0639 \u0623\u0648 \u0631\u0624\u064a\u0629 \u0623\u0634\u064a\u0627\u0621 \u063a\u064a\u0631 \u0645\u0648\u062c\u0648\u062f\u0629 \u060c \u0645\u062b\u0644 \u0627\u0644\u0623\u0635\u0648\u0627\u062a. \u064a\u0645\u0643\u0646 \u0644\u0644\u0623\u0635\u0648\u0627\u062a \u0623\u0646 \u062a\u062e\u0628\u0631\u0643 \u0628\u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u062a\u064a \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0623\u062f\u0627\u0626\u0647\u0627 \u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644. \u0641\u064a \u0627\u0644\u062d\u0627\u0644\u0627\u062a \u0627\u0644\u0634\u062f\u064a\u062f\u0629 \u060c \u064a\u0645\u0643\u0646 \u0623\u0646 \u062a\u062c\u0639\u0644\u0643 \u0627\u0644\u0647\u0644\u0648\u0633\u0629 \u062a\u0641\u0643\u0631 \u0641\u064a \u0627\u0644\u0627\u0646\u062a\u062d\u0627\u0631.<\/li>\n<li>\u0627\u0644\u0641\u0648\u0636\u064a. \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u062d\u0627\u0644\u0629 \u060c \u064a\u0648\u0627\u062c\u0647 \u0634\u062e\u0635 \u0645\u0627 \u0635\u0639\u0648\u0628\u0629 \u0641\u064a \u0625\u062d\u0644\u0627\u0644 \u0627\u0644\u0646\u0638\u0627\u0645 \u0641\u064a \u062d\u064a\u0627\u062a\u0647. \u0639\u0627\u062f\u0629 \u0645\u0627 \u064a\u0648\u0627\u062c\u0647 \u0627\u0644\u0646\u0627\u0633 \u0635\u0639\u0648\u0628\u0629 \u0641\u064a \u0641\u0639\u0644 \u0623\u0634\u064a\u0627\u0621 \u0645\u0639\u064a\u0646\u0629 \u0623\u0648 \u0627\u0644\u062a\u0641\u0643\u064a\u0631 \u0641\u064a\u0647\u0627 \u0623\u0648 \u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0647\u0627. \u0645\u062b\u0627\u0644 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0647\u0648 \u0623\u0646 \u0634\u062e\u0635\u0627 \u0645\u0627 \u064a\u0646\u0641\u062c\u0631 \u0641\u064a \u0627\u0644\u0628\u0643\u0627\u0621 \u0641\u064a \u0645\u0648\u0642\u0641 \u0644\u0627 \u064a\u0641\u0647\u0645\u0647 \u0627\u0644\u0622\u062e\u0631\u0648\u0646.<\/li>\n<\/ul>\n<p>\u064a\u062c\u0639\u0644 \u0627\u0644\u0630\u0647\u0627\u0646 \u0645\u0646 \u0627\u0644\u0635\u0639\u0628 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0639\u0644\u0649 \u0623\u0646\u0634\u0637\u062a\u0643 \u0627\u0644\u064a\u0648\u0645\u064a\u0629 \u0648\u062a\u0648\u0627\u062c\u0647 \u0635\u0639\u0648\u0628\u0629 \u0641\u064a \u0625\u062c\u0631\u0627\u0621 \u0645\u062d\u0627\u062f\u062b\u0627\u062a.<\/p>\n"},{"title":"\u0645\u0627\u0630\u0627 \u064a\u0645\u0643\u0646\u0646\u064a \u0623\u0646 \u0623\u0641\u0639\u0644 \u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646\u061f","content":"<p>\u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0639\u0627\u0646\u064a \u0645\u0646 \u0627\u0644\u0630\u0647\u0627\u0646 \u0628\u0646\u0641\u0633\u0643 \u060c \u0641\u0645\u0646 \u0627\u0644\u0645\u0647\u0645 \u0637\u0644\u0628 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629. \u0628\u0639\u0636 \u0627\u0644\u0646\u0635\u0627\u0626\u062d \u0644\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0642\u0627\u0628\u0644\u064a\u0629 \u0644\u0644\u0630\u0647\u0627\u0646 \u0647\u064a:<\/p>\n<ul>\n<li>\u062a\u062d\u062f\u062b \u0639\u0646 \u0627\u0644\u0630\u0647\u0627\u0646 \u0645\u0639 \u0623\u062d\u0628\u0627\u0626\u0643\u060c \u0645\u062b\u0644 \u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0623\u0648 \u0627\u0644\u0639\u0627\u0626\u0644\u0629 \u0623\u0648 \u0634\u0631\u064a\u0643\u0643. \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0628\u0639\u0636 \u0627\u0644\u0646\u0627\u0633 \u060c \u0642\u062f \u064a\u0643\u0648\u0646 \u0645\u0646 \u0627\u0644\u062c\u064a\u062f \u062c\u062f\u0627 \u0627\u0644\u062a\u0646\u0641\u064a\u0633. \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0630\u0644\u0643 \u060c \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u062c\u0639\u0644\u0643 \u062a\u0634\u0639\u0631 \u0648\u0643\u0623\u0646\u0643 \u0644\u0633\u062a \u0648\u062d\u062f\u0643.<\/li>\n<li>\u062a\u062d\u062f\u062b \u0639\u0646 \u0627\u0644\u0630\u0647\u0627\u0646 \u0645\u0639 \u0632\u0645\u0644\u0627\u0626\u0643 \u0627\u0644\u0645\u0635\u0627\u0628\u064a\u0646. \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0643\u0648\u0646 \u0647\u0624\u0644\u0627\u0621 \u0623\u0634\u062e\u0627\u0635\u0627 \u064a\u0639\u0627\u0646\u0648\u0646 \u0623\u064a\u0636\u0627 \u0645\u0646 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0645\u0639\u0631\u0636\u064a\u0646 \u0644\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0630\u0647\u0627\u0646. \u064a\u0645\u0643\u0646\u0647\u0645 \u0625\u062e\u0628\u0627\u0631\u0643 \u0628\u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u0630\u0644\u0643 \u060c \u0644\u0623\u0646\u0647\u0645 \u0641\u064a \u0646\u0641\u0633 \u0627\u0644\u0645\u0648\u0642\u0641.<\/li>\n<li>\u0627\u0628\u062d\u062b \u0639\u0646 \u0627\u0644\u0627\u0633\u062a\u0631\u062e\u0627\u0621 \u0625\u0630\u0627 \u0648\u062c\u062f\u062a \u0646\u0641\u0633\u0643 \u0645\u062a\u0648\u062a\u0631\u0627 \u0644\u0644\u063a\u0627\u064a\u0629.<\/li>\n<li>\u062a\u062c\u0646\u0628 \u062a\u0639\u0627\u0637\u064a \u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a \u0648\u0627\u0644\u0643\u062d\u0648\u0644. \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0624\u062f\u064a \u0647\u0630\u0627\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0646 \u0625\u0644\u0649 \u062a\u0641\u0627\u0642\u0645 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u062d\u062a\u0649 \u062a\u062d\u0641\u064a\u0632\u0647\u0645\u0627.<\/li>\n<li>\u0627\u0637\u0644\u0628 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0645\u0646 \u0645\u062d\u062a\u0631\u0641. \u0644\u0647\u0630\u0627 \u060c \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0628\u0637\u0628\u064a\u0628\u0643 \u0627\u0644\u0639\u0627\u0645 \u060c \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0625\u062d\u0627\u0644\u062a\u0643 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0645\u0646\u0627\u0633\u0628.<\/li>\n<\/ul>\n"},{"title":"\u0645\u062a\u0649 \u064a\u062c\u0628 \u0623\u0646 \u0623\u0631\u0649 \u0627\u0644\u0637\u0628\u064a\u0628 \u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646\u061f","content":"<p>\u0627\u062a\u0635\u0644 \u0628\u0637\u0628\u064a\u0628\u0643 \u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0639\u0627\u0646\u064a \u0645\u0646 \u0623\u0639\u0631\u0627\u0636 \u0645\u0628\u0643\u0631\u0629 \u0644\u0644\u0630\u0647\u0627\u0646. \u0627\u0634\u0631\u062d \u0644\u0637\u0628\u064a\u0628\u0643 \u0627\u0644\u0639\u0627\u0645 \u0645\u0627 \u062a\u0634\u0639\u0631 \u0628\u0647. \u0633\u064a\u0639\u0645\u0644 \u0627\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0639\u0627\u0645 \u0645\u0639\u0643 \u0644\u0644\u0639\u062b\u0648\u0631 \u0639\u0644\u0649 \u0623\u0641\u0636\u0644 \u0639\u0644\u0627\u062c \u0644\u0643.<\/p>\n<p>\u0625\u0630\u0627 \u0643\u0646\u062a \u062d\u0627\u0644\u064a\u0627 \u0641\u064a \u062d\u0627\u0644\u0629 \u0630\u0647\u0627\u0646 \u060c \u0641\u0645\u0646 \u0627\u0644\u0645\u0647\u0645 \u0623\u0646 \u062a\u062a\u0635\u0644 \u0623\u064a\u0636\u0627 \u0628\u0637\u0628\u064a\u0628\u0643 \u0627\u0644\u0639\u0627\u0645. \u064a\u0645\u0643\u0646 \u0644\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0639\u0627\u0645 \u0625\u062d\u0627\u0644\u062a\u0643 \u0625\u0644\u0649 \u0645\u0646\u0638\u0645\u0629 \u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0645\u0646\u0627\u0633\u0628.<\/p>\n<p>\u0627\u062a\u0635\u0644 \u0628\u0627\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0639\u0627\u0645 \u0623\u0648 \u062e\u0637 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 0900-0113 \u0639\u0644\u0649 \u0627\u0644\u0641\u0648\u0631 \u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0641\u0643\u0631 \u0641\u064a \u0627\u0644\u0645\u0648\u062a \u0648 \/ \u0623\u0648 \u0625\u0630\u0627 \u0643\u0627\u0646\u062a \u0644\u062f\u064a\u0643 \u062e\u0637\u0637 \u0644\u0625\u0646\u0647\u0627\u0621 \u062d\u064a\u0627\u062a\u0643.<\/p>\n"}],"original_post_id":"5_482","disable_sync":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0627\u0644\u0630\u0647\u0627\u0646 - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a<\/title>\n<meta name=\"description\" content=\"\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u0627\u0644\u0630\u0647\u0627\u0646\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0644\u0630\u0647\u0627\u0646 - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\" \/>\n<meta property=\"og:description\" content=\"\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u0627\u0644\u0630\u0647\u0627\u0646\/\" \/>\n<meta property=\"og:site_name\" content=\"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\\\/\",\"url\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\\\/\",\"name\":\"\u0627\u0644\u0630\u0647\u0627\u0646 - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/#website\"},\"datePublished\":\"2025-05-26T12:54:37+00:00\",\"description\":\"\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0634\u0643\u0627\u0648\u0649 \u0627\u0644\u0635\u062d\u064a\u0629\",\"item\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/shakawi-sihhiya\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0627\u0644\u0630\u0647\u0627\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/\",\"name\":\"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/huisartsenpostenamsterdam.nl\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u0630\u0647\u0627\u0646 - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","description":"\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u0627\u0644\u0630\u0647\u0627\u0646\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0627\u0644\u0630\u0647\u0627\u0646 - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","og_description":"\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646.","og_url":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/\u0627\u0644\u0630\u0647\u0627\u0646\/","og_site_name":"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/","url":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/","name":"\u0627\u0644\u0630\u0647\u0627\u0646 - Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","isPartOf":{"@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/#website"},"datePublished":"2025-05-26T12:54:37+00:00","description":"\u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u0630\u0647\u0627\u0646 \u060c \u0641\u0642\u062f \u0634\u062e\u0635 \u0645\u0627 \u0642\u0628\u0636\u062a\u0647 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u0642\u0639. \u0627\u0642\u0631\u0623 \u0647\u0646\u0627 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0645\u0639 \u0627\u0644\u0630\u0647\u0627\u0646 \u0623\u0648 \u0627\u0644\u0630\u0647\u0627\u0646.","breadcrumb":{"@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/%d8%a7%d9%84%d8%b0%d9%87%d8%a7%d9%86\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0634\u0643\u0627\u0648\u0649 \u0627\u0644\u0635\u062d\u064a\u0629","item":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/shakawi-sihhiya\/"},{"@type":"ListItem","position":3,"name":"\u0627\u0644\u0630\u0647\u0627\u0646"}]},{"@type":"WebSite","@id":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/#website","url":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/","name":"Huisartsenposten Amsterdam - \u0639\u0631\u0628\u064a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint\/53160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint"}],"about":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/types\/complaint"}],"wp:attachment":[{"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/media?parent=53160"}],"wp:term":[{"taxonomy":"complaint_tag","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_tag?post=53160"},{"taxonomy":"complaint_body_part","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_body_part?post=53160"},{"taxonomy":"complaint_age_group","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_age_group?post=53160"},{"taxonomy":"complaint_category","embeddable":true,"href":"https:\/\/huisartsenpostenamsterdam.nl\/ar\/wp-json\/wp\/v2\/complaint_category?post=53160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}